{"id":2231,"date":"2023-10-05T14:49:56","date_gmt":"2023-10-05T12:49:56","guid":{"rendered":"https:\/\/oikos-church.ch\/?post_type=sermon_videos&#038;p=2231"},"modified":"2023-10-05T14:49:56","modified_gmt":"2023-10-05T12:49:56","slug":"the-incorruptible-inheritance-das-unverwelkliche-oikos-international-church-gottesdienst","status":"publish","type":"sermon_videos","link":"https:\/\/oikos-church.ch\/de\/sermon_videos\/the-incorruptible-inheritance-das-unverwelkliche-oikos-international-church-gottesdienst\/","title":{"rendered":"The incorruptible inheritance\/ Das unverwelkliche  &#8211; Oikos International Church Gottesdienst"},"content":{"rendered":"<p>Redner: Silvia Nickelson<\/p>\n<p>zu einem unverg\u00e4nglichen und unbefleckten und unverwelklichen Erbe, das im Himmel aufbewahrt wird f\u00fcr uns<br \/>\n1 Petrus 1:4<\/p>\n<p>To an inheritance incorruptible, and undefiled, and that fadeth not away, reserved in heaven for you,<br \/>\n1 Peter 1:4<\/p>","protected":false},"excerpt":{"rendered":"<p>Redner: Silvia Nickelson zu einem unverg\u00e4nglichen und unbefleckten und unverwelklichen Erbe, das im Himmel aufbewahrt wird f\u00fcr uns 1 Petrus 1:4 To an inheritance incorruptible, and undefiled, and that fadeth not away, reserved in heaven for you, 1 Peter 1:4<\/p>","protected":false},"author":1,"featured_media":2232,"template":"","meta":{"_acf_changed":false},"class_list":["post-2231","sermon_videos","type-sermon_videos","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/oikos-church.ch\/de\/wp-json\/wp\/v2\/sermon_videos\/2231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oikos-church.ch\/de\/wp-json\/wp\/v2\/sermon_videos"}],"about":[{"href":"https:\/\/oikos-church.ch\/de\/wp-json\/wp\/v2\/types\/sermon_videos"}],"author":[{"embeddable":true,"href":"https:\/\/oikos-church.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/oikos-church.ch\/de\/wp-json\/wp\/v2\/media\/2232"}],"wp:attachment":[{"href":"https:\/\/oikos-church.ch\/de\/wp-json\/wp\/v2\/media?parent=2231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}