{"id":2229,"date":"2023-09-28T13:45:30","date_gmt":"2023-09-28T11:45:30","guid":{"rendered":"https:\/\/oikos-church.ch\/?post_type=sermon_videos&#038;p=2229"},"modified":"2023-09-28T13:45:30","modified_gmt":"2023-09-28T11:45:30","slug":"gottesdienst-24-09-2023-interview-mit-simon-schaub","status":"publish","type":"sermon_videos","link":"https:\/\/oikos-church.ch\/de\/sermon_videos\/gottesdienst-24-09-2023-interview-mit-simon-schaub\/","title":{"rendered":"Gottesdienst 24.09.2023 Interview Mit Simon Schaub"},"content":{"rendered":"<p>Gottesdienst 24.09.2023 Interview Mit Simon Schaub<\/p>","protected":false},"excerpt":{"rendered":"<p>Gottesdienst 24.09.2023 Interview Mit Simon Schaub<\/p>","protected":false},"author":1,"featured_media":2230,"template":"","meta":{"_acf_changed":false},"class_list":["post-2229","sermon_videos","type-sermon_videos","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/oikos-church.ch\/de\/wp-json\/wp\/v2\/sermon_videos\/2229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oikos-church.ch\/de\/wp-json\/wp\/v2\/sermon_videos"}],"about":[{"href":"https:\/\/oikos-church.ch\/de\/wp-json\/wp\/v2\/types\/sermon_videos"}],"author":[{"embeddable":true,"href":"https:\/\/oikos-church.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/oikos-church.ch\/de\/wp-json\/wp\/v2\/media\/2230"}],"wp:attachment":[{"href":"https:\/\/oikos-church.ch\/de\/wp-json\/wp\/v2\/media?parent=2229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}