{"id":2022,"date":"2022-02-20T14:33:37","date_gmt":"2022-02-20T13:33:37","guid":{"rendered":"https:\/\/oikos-church.ch\/?post_type=sermon_videos&#038;p=2022"},"modified":"2023-01-11T14:35:08","modified_gmt":"2023-01-11T13:35:08","slug":"gottesdienst-20-02-2022-the-prophetic-spirit-der-prophetische-geist-silvia-nickelson-en-de","status":"publish","type":"sermon_videos","link":"https:\/\/oikos-church.ch\/de\/sermon_videos\/gottesdienst-20-02-2022-the-prophetic-spirit-der-prophetische-geist-silvia-nickelson-en-de\/","title":{"rendered":"Gottesdienst 20.02.2022 &#8211; The Prophetic Spirit\/Der prophetische Geist | Silvia Nickelson (EN\/DE)"},"content":{"rendered":"<p>Und so halten wir nun fest<br \/>\nan dem v\u00f6llig gewissen prophetischen Wort,<br \/>\nund ihr tut gut daran, darauf zu achten<br \/>\nals auf ein Licht, das an einem dunklen Ort scheint,<br \/>\nbis der Tag anbricht und der Morgenstern aufgeht<br \/>\nin euren Herzen.<br \/>\n2. Petrus 1, 19<\/p>\n<p>And so we have the prophetic word confirmed,<br \/>\nwhich you do well to heedas a light that shines in a dark place,<br \/>\nuntil the day dawns and the morning star rises<br \/>\nin your hearts.<br \/>\n2 Peter 1:19<\/p>","protected":false},"excerpt":{"rendered":"<p>Und so halten wir nun fest an dem v\u00f6llig gewissen prophetischen Wort, und ihr tut gut daran, darauf zu achten als auf ein Licht, das an einem dunklen Ort scheint, bis der Tag anbricht und der Morgenstern aufgeht in euren Herzen. 2. Petrus 1, 19 And so we have the prophetic word confirmed, which you [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2023,"template":"","meta":{"_acf_changed":false},"class_list":["post-2022","sermon_videos","type-sermon_videos","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/oikos-church.ch\/de\/wp-json\/wp\/v2\/sermon_videos\/2022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oikos-church.ch\/de\/wp-json\/wp\/v2\/sermon_videos"}],"about":[{"href":"https:\/\/oikos-church.ch\/de\/wp-json\/wp\/v2\/types\/sermon_videos"}],"author":[{"embeddable":true,"href":"https:\/\/oikos-church.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/oikos-church.ch\/de\/wp-json\/wp\/v2\/media\/2023"}],"wp:attachment":[{"href":"https:\/\/oikos-church.ch\/de\/wp-json\/wp\/v2\/media?parent=2022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}